{"id":953,"date":"2024-03-27T06:30:00","date_gmt":"2024-03-27T06:30:00","guid":{"rendered":"https:\/\/pouparinvestirlucrar.com\/?p=953"},"modified":"2024-03-17T15:21:14","modified_gmt":"2024-03-17T15:21:14","slug":"a-inflacao-e-a-historia-do-dinheiro","status":"publish","type":"post","link":"https:\/\/pouparinvestirlucrar.com\/index.php\/2024\/03\/27\/a-inflacao-e-a-historia-do-dinheiro\/","title":{"rendered":"A Infla\u00e7\u00e3o e a Hist\u00f3ria do Dinheiro"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"686\" src=\"https:\/\/pouparinvestirlucrar.com\/wp-content\/uploads\/2024\/03\/Historia-do-dinheiro-1024x686.jpg\" alt=\"\" class=\"wp-image-954\" style=\"width:336px;height:auto\" srcset=\"https:\/\/pouparinvestirlucrar.com\/wp-content\/uploads\/2024\/03\/Historia-do-dinheiro-1024x686.jpg 1024w, https:\/\/pouparinvestirlucrar.com\/wp-content\/uploads\/2024\/03\/Historia-do-dinheiro-300x201.jpg 300w, https:\/\/pouparinvestirlucrar.com\/wp-content\/uploads\/2024\/03\/Historia-do-dinheiro-768x514.jpg 768w, https:\/\/pouparinvestirlucrar.com\/wp-content\/uploads\/2024\/03\/Historia-do-dinheiro-1536x1028.jpg 1536w, https:\/\/pouparinvestirlucrar.com\/wp-content\/uploads\/2024\/03\/Historia-do-dinheiro-2048x1371.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Sejam bem-vindos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para come\u00e7armos a hist\u00f3ria do dinheiro, temos de recuar bastante no tempo, at\u00e9 cerca de 10.000 antes de cristo. Nessa altura ainda n\u00e3o exista o conceito de dinheiro. As pessoas trocavam bens e servi\u00e7os uns com os outros. Era normal n\u00e3o chegarem a acordo, fosse pelo valor dos produtos, fosse por n\u00e3o haver interesse no artigo da troca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nasce assim, o conceito de mercadoria ou bens de conveni\u00eancia, que eram utilizados por todos, para as trocas. A t\u00edtulo de exemplo, era o ch\u00e1, o sal, tabaco, gado ou at\u00e9 as sementes. Mas n\u00e3o era pr\u00e1tico, devido \u00e0s dificuldades de transporte e de armazenamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na antiga L\u00eddia (reino antigo da Anat\u00f3lia, hoje Turquia), os objetos de metal foram introduzidos como objetos de troca, criando o conceito de dinheiro cerca de 5.000 a.c. Os territ\u00f3rios come\u00e7aram assim a procura por diferentes min\u00e9rios, para tamb\u00e9m cunharem o seu min\u00e9rio e assim o identificarem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O metal era usado por estar facilmente dispon\u00edvel, por ser f\u00e1cil de trabalhar e por ser reutiliz\u00e1vel para outras fun\u00e7\u00f5es. Assim foram dados diferentes valores \u00e0s moedas, come\u00e7ou assim a ser mais f\u00e1cil comparar o custo das diversas mercadorias e dos objetos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a introdu\u00e7\u00e3o do papel-moeda e a cunhagem de metais n\u00e3o preciosos, o dinheiro tornou-se representativo, ou seja, o material de que era feito deixou de ser valioso \u201cper si\u201d. Algum do papel-moeda data de 960 d.c. sendo a descoberta mais antiga na China, e desde a\u00ed vulgarizou-se.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A quantidade produzida deste papel-moeda sempre foi diretamente suportada por uma quantidade equivalente em ouro ou prata dos bancos ou governos. Passou-se, depois, a utilizar dinheiro representativo com o seu valor atribu\u00eddo legalmente ou por decretos do governo, j\u00e1 n\u00e3o era necess\u00e1rio o equivalente ao metal precioso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a introdu\u00e7\u00e3o do papel-moeda, sempre que um governo queira \u201ccriar mais riqueza\u201d, ou colocar mais dinheiro em circula\u00e7\u00e3o, apenas tem de produzir mais dinheiro. Isto faz com que o valor do dinheiro diminua, fazendo com que os pre\u00e7os e a taxa de infla\u00e7\u00e3o subam. A infla\u00e7\u00e3o tem a caracter\u00edstica de criar esta ilus\u00e3o de riqueza, mesmo que tudo continue igual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A esta tend\u00eancia de subida dos pre\u00e7os de ano para ano chama-se infla\u00e7\u00e3o, n\u00e3o se aplicando a subidas ocasionais nem \u00e0s que atingem um \u00fanico produto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se tiveres alguma d\u00favida ou precisares de algum esclarecimento sobre este ou outro tema, envia-me um email para <a href=\"mailto:pouparinvestirlucrar@gmail.com\">pouparinvestirlucrar@gmail.com<\/a> que terei todo o gosto em te ajudar.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Por isso e por tudo o que ainda vais ver, segue o blog para n\u00e3o perderes nenhum artigo! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DIsclaimer \u2013 Este site apenas tem fins informativos e educacionais. As opini\u00f5es expressas aqui s\u00e3o as do autor e n\u00e3o necessariamente refletem as opini\u00f5es de qualquer empresa ou entidade mencionada. O conte\u00fado deste site n\u00e3o deve ser interpretado como conselhos financeiros profissionais. Consulte um conselheiro financeiro qualificado antes de tomar qualquer decis\u00e3o financeira importante. O autor deste site n\u00e3o se responsabiliza por qualquer perda ou danos decorrentes do uso do conte\u00fado deste site.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sejam bem-vindos! Para come\u00e7armos a hist\u00f3ria do dinheiro, temos de recuar bastante no tempo, at\u00e9 cerca de 10.000 antes de cristo. Nessa altura ainda n\u00e3o exista o conceito de dinheiro. As pessoas trocavam bens e servi\u00e7os uns com os outros. Era normal n\u00e3o chegarem a acordo, fosse pelo valor dos produtos, fosse por n\u00e3o haver [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-953","post","type-post","status-publish","format-standard","hentry","category-financas-pessoais"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"jpvpaulo","author_link":"https:\/\/pouparinvestirlucrar.com\/author\/jpvpaulo\/"},"uagb_comment_info":0,"uagb_excerpt":"Sejam bem-vindos! Para come\u00e7armos a hist\u00f3ria do dinheiro, temos de recuar bastante no tempo, at\u00e9 cerca de 10.000 antes de cristo. Nessa altura ainda n\u00e3o exista o conceito de dinheiro. As pessoas trocavam bens e servi\u00e7os uns com os outros. Era normal n\u00e3o chegarem a acordo, fosse pelo valor dos produtos, fosse por n\u00e3o haver&hellip;","_links":{"self":[{"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/posts\/953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/comments?post=953"}],"version-history":[{"count":1,"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/posts\/953\/revisions"}],"predecessor-version":[{"id":955,"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/posts\/953\/revisions\/955"}],"wp:attachment":[{"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/media?parent=953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/categories?post=953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pouparinvestirlucrar.com\/index.php\/wp-json\/wp\/v2\/tags?post=953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}